{"id":105378,"date":"2023-10-05T11:02:57","date_gmt":"2023-10-05T17:02:57","guid":{"rendered":"https:\/\/www.wellogi.com\/cursos\/?post_type=lesson&#038;p=105378"},"modified":"2024-01-04T09:09:17","modified_gmt":"2024-01-04T15:09:17","slug":"mentoria-exclusiva-del-4-octubre-2023","status":"publish","type":"lesson","link":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/","title":{"rendered":"Mentor\u00eda Exclusiva del 4-octubre-2023"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_initial_content":"","_new_post":false,"_quiz_has_questions":false,"_lesson_complexity":"easy","_lesson_length":90,"_lesson_course":28898,"_lesson_preview":""},"lesson-tag":[],"class_list":["post-105378","lesson","type-lesson","status-publish","post-password-required","hentry","module-mentoria-clase-grabada-del-ultimo-miercoles","post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy<\/title>\n<meta name=\"description\" content=\"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona especializada en Nutricion, Entrenamiento, Recomposici\u00f3n Corporal, Fitness y Wellness.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy\" \/>\n<meta property=\"og:description\" content=\"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona especializada en Nutricion, Entrenamiento, Recomposici\u00f3n Corporal, Fitness y Wellness.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Wellogi Academy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/WellogiApp\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T15:09:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Wellogi_App\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/lecci\u00f3n\\\/mentoria-exclusiva-del-4-octubre-2023\\\/\",\"url\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/lecci\u00f3n\\\/mentoria-exclusiva-del-4-octubre-2023\\\/\",\"name\":\"Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#website\"},\"datePublished\":\"2023-10-05T17:02:57+00:00\",\"dateModified\":\"2024-01-04T15:09:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/lecci\u00f3n\\\/mentoria-exclusiva-del-4-octubre-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#website\",\"url\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/\",\"name\":\"Wellogi Academy\",\"description\":\"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#organization\",\"name\":\"Wellogi Academy\",\"url\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-y-Slogan-transparente-final-.png\",\"contentUrl\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Logo-y-Slogan-transparente-final-.png\",\"width\":5042,\"height\":4883,\"caption\":\"Wellogi Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wellogi.com\\\/cursos\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/WellogiApp\",\"https:\\\/\\\/x.com\\\/Wellogi_App\",\"https:\\\/\\\/www.instagram.com\\\/wellogi_app\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luis-gomez-wellogi\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Wellogi\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy","description":"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona especializada en Nutricion, Entrenamiento, Recomposici\u00f3n Corporal, Fitness y Wellness.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/","og_locale":"es_MX","og_type":"article","og_title":"Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy","og_description":"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona especializada en Nutricion, Entrenamiento, Recomposici\u00f3n Corporal, Fitness y Wellness.","og_url":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/","og_site_name":"Wellogi Academy","article_publisher":"https:\/\/www.facebook.com\/WellogiApp","article_modified_time":"2024-01-04T15:09:17+00:00","twitter_card":"summary_large_image","twitter_site":"@Wellogi_App","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/","url":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/","name":"Mentor\u00eda Exclusiva del 4-octubre-2023 - Wellogi Academy","isPartOf":{"@id":"https:\/\/www.wellogi.com\/cursos\/#website"},"datePublished":"2023-10-05T17:02:57+00:00","dateModified":"2024-01-04T15:09:17+00:00","breadcrumb":{"@id":"https:\/\/www.wellogi.com\/cursos\/lecci\u00f3n\/mentoria-exclusiva-del-4-octubre-2023\/#breadcrumb"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/www.wellogi.com\/cursos\/#website","url":"https:\/\/www.wellogi.com\/cursos\/","name":"Wellogi Academy","description":"Plataforma de capacitaci\u00f3n acad\u00e9mica continua as\u00edncrona.","publisher":{"@id":"https:\/\/www.wellogi.com\/cursos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wellogi.com\/cursos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.wellogi.com\/cursos\/#organization","name":"Wellogi Academy","url":"https:\/\/www.wellogi.com\/cursos\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.wellogi.com\/cursos\/#\/schema\/logo\/image\/","url":"https:\/\/www.wellogi.com\/cursos\/wp-content\/uploads\/2021\/11\/Logo-y-Slogan-transparente-final-.png","contentUrl":"https:\/\/www.wellogi.com\/cursos\/wp-content\/uploads\/2021\/11\/Logo-y-Slogan-transparente-final-.png","width":5042,"height":4883,"caption":"Wellogi Academy"},"image":{"@id":"https:\/\/www.wellogi.com\/cursos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/WellogiApp","https:\/\/x.com\/Wellogi_App","https:\/\/www.instagram.com\/wellogi_app\/","https:\/\/www.linkedin.com\/in\/luis-gomez-wellogi\/","https:\/\/www.youtube.com\/c\/Wellogi\/videos"]}]}},"is_coteacher":false,"_links":{"self":[{"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/lessons\/105378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/lessons"}],"about":[{"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/types\/lesson"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/comments?post=105378"}],"version-history":[{"count":4,"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/lessons\/105378\/revisions"}],"predecessor-version":[{"id":108273,"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/lessons\/105378\/revisions\/108273"}],"wp:attachment":[{"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/media?parent=105378"}],"wp:term":[{"taxonomy":"lesson-tag","embeddable":true,"href":"https:\/\/www.wellogi.com\/cursos\/wp-json\/wp\/v2\/lesson-tag?post=105378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}